{"id":24644,"date":"2026-04-22T00:13:26","date_gmt":"2026-04-22T06:13:26","guid":{"rendered":"https:\/\/antiguafinehomes.com\/property\/casa-nueva-de-3-dormitorios-con-terraza-en-residencial-antigua-gardens\/"},"modified":"2026-05-10T23:18:00","modified_gmt":"2026-05-11T05:18:00","slug":"casa-nueva-de-3-dormitorios-con-terraza-en-residencial-antigua-gardens","status":"publish","type":"property","link":"https:\/\/antiguafinehomes.com\/es\/property\/casa-nueva-de-3-dormitorios-con-terraza-en-residencial-antigua-gardens\/","title":{"rendered":"Casa Nueva de 3 Dormitorios con Terraza en Residencial \u2013 Antigua Gardens"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Casa completamente nueva en venta dentro de Antigua Gardens, un residencial que combina comodidad, seguridad y excelentes amenidades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><p>El condominio ofrece garita con control de acceso y seguridad 24\/7, as&iacute; como mantenimiento constante y limpieza de las &aacute;reas verdes comunes, brindando un entorno ordenado, seguro y agradable para toda la familia. La propiedad est&aacute; dise&ntilde;ada en dos niveles, con espacios funcionales y bien iluminados que aprovechan al m&aacute;ximo cada &aacute;rea.<\/p>\n<br>\n<br><p>En el primer nivel encontrara una acogedora sala y comedor integrados, ideales para compartir en familia o recibir visitas, adem&aacute;s de una cocina equipada con gabinetes que ofrecen buen espacio de almacenamiento. Tambi&eacute;n cuenta con ba&ntilde;o de visitas, un peque&ntilde;o patio con pila y &aacute;rea designada para lavander&iacute;a.<\/p>\n<br>\n<br><p>En el segundo nivel se ubican tres amplios dormitorios. La habitaci&oacute;n principal dispone de ba&ntilde;o privado, mientras que las habitaciones secundarias comparten un ba&ntilde;o completo. Desde este nivel se aprecian agradables vistas, y la propiedad se complementa con una amplia terraza perfecta para disfrutar del clima, relajarse o crear un espacio al aire libre. Antigua Gardens ofrece amenidades que elevan la calidad de vida de sus residentes, incluyendo gimnasio, sauna, piscina de gran tama&ntilde;o y canchas deportivas de f&uacute;tbol y baloncesto.<\/p>\n<br>\n<br><p>Su excelente ubicaci&oacute;n permite f&aacute;cil acceso a la carretera principal y se encuentra a tan solo 25 minutos del centro de La  Antigua Guatemala, combinando tranquilidad con cercan&iacute;a a todos los servicios. Una excelente oportunidad para vivir o invertir en una propiedad nueva dentro de un residencial completo y bien ubicado. Para agendar una cita o recibir m&aacute;s informaci&oacute;n, comun&iacute;cate con Isabel Morales<\/p>\n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Casa completamente nueva en venta dentro de Antigua Gardens, un residencial que combina comodidad, seguridad y excelentes amenidades.<\/p>\n","protected":false},"author":11,"featured_media":24633,"parent":0,"menu_order":0,"template":"","property_type":[328],"property_status":[503],"property_feature":[741,726,729,725,740,727,742,743,744],"property_label":[],"property_state":[263],"property_city":[268],"property_area":[645],"class_list":["post-24644","property","type-property","status-publish","has-post-thumbnail","hentry","property_type-casa","property_status-en-venta","property_feature-cancha-de-tenis","property_feature-casa-club","property_feature-cupula","property_feature-frente-al-mar-vista-al-mar","property_feature-piscina","property_feature-piscina-comunitaria","property_feature-terraza","property_feature-vista-a-los-volcanes","property_feature-walk-in-closet","property_state-area-de-antigua","property_city-alotenango","property_area-antigua-gardens"],"property_meta":{"_wp_page_template":["default"],"rank_math_internal_links_processed":["1"],"copied_media_ids":["a:0:{}"],"referenced_media_ids":["a:0:{}"],"fave_currency":["USD"],"fave_currency_info":["a:8:{s:2:\"id\";s:1:\"1\";s:13:\"currency_name\";s:21:\"United States Dollars\";s:13:\"currency_code\";s:3:\"USD\";s:15:\"currency_symbol\";s:1:\"$\";s:17:\"currency_position\";s:6:\"before\";s:16:\"currency_decimal\";s:1:\"2\";s:26:\"currency_decimal_separator\";s:1:\".\";s:27:\"currency_thousand_separator\";s:1:\",\";}"],"fave_property_price":["350000.00"],"fave_property_size":["220.00"],"fave_property_land":["112.50"],"fave_property_bedrooms":["3"],"fave_property_bathrooms":["2.50"],"fave_property_garage":["1"],"fave_property_map":["1"],"fave_featured":["0"],"houzez_featured_listing_date":[""],"fave_agent_display_option":["agent_info"],"fave_prop_homeslider":["no"],"fave_additional_features_enable":["disable"],"floor_plans":[null],"fave_multi_units":[null],"additional_features":[null],"fave_agents":["19808"],"fave_property_map_address":["Alotenango, Guatemala"],"houzez_geolocation_lat":["14.48062"],"houzez_geolocation_long":["-90.80253"],"fave_gated-community":["Gated Community"],"fave_property_id":["1780"],"fave_varas":["1600044.00"],"_wpml_word_count":["357"],"_wpml_location_migration_done":["1"],"fave_video_url":[null],"fave_property_price_postfix":[null],"fave_property_sec_price":[null],"fave_property_price_prefix":[null],"fave_property_size_prefix":[null],"fave_property_land_postfix":[null],"fave_property_garage_size":[null],"fave_property_year":[null],"fave_property_map_street_view":[null],"fave_property_zip":[null],"houzez_total_property_views":["170"],"houzez_views_by_date":["a:57:{s:10:\"05-11-2026\";i:4;s:10:\"05-13-2026\";i:1;s:10:\"05-14-2026\";i:5;s:10:\"05-15-2026\";i:6;s:10:\"05-16-2026\";i:3;s:10:\"05-17-2026\";i:1;s:10:\"05-19-2026\";i:2;s:10:\"05-20-2026\";i:2;s:10:\"05-21-2026\";i:3;s:10:\"05-23-2026\";i:2;s:10:\"05-24-2026\";i:1;s:10:\"05-25-2026\";i:1;s:10:\"05-26-2026\";i:3;s:10:\"05-28-2026\";i:1;s:10:\"05-29-2026\";i:1;s:10:\"05-30-2026\";i:2;s:10:\"05-31-2026\";i:1;s:10:\"06-01-2026\";i:1;s:10:\"06-02-2026\";i:2;s:10:\"06-03-2026\";i:2;s:10:\"06-04-2026\";i:2;s:10:\"06-05-2026\";i:1;s:10:\"06-06-2026\";i:1;s:10:\"06-07-2026\";i:3;s:10:\"06-09-2026\";i:1;s:10:\"06-10-2026\";i:1;s:10:\"06-12-2026\";i:1;s:10:\"06-14-2026\";i:2;s:10:\"06-15-2026\";i:1;s:10:\"06-17-2026\";i:1;s:10:\"06-18-2026\";i:1;s:10:\"06-19-2026\";i:2;s:10:\"06-20-2026\";i:1;s:10:\"06-21-2026\";i:2;s:10:\"06-22-2026\";i:4;s:10:\"06-23-2026\";i:1;s:10:\"06-24-2026\";i:2;s:10:\"06-25-2026\";i:3;s:10:\"06-26-2026\";i:1;s:10:\"06-28-2026\";i:6;s:10:\"06-29-2026\";i:3;s:10:\"06-30-2026\";i:2;s:10:\"07-01-2026\";i:4;s:10:\"07-02-2026\";i:5;s:10:\"07-03-2026\";i:2;s:10:\"07-04-2026\";i:6;s:10:\"07-05-2026\";i:3;s:10:\"07-06-2026\";i:4;s:10:\"07-07-2026\";i:11;s:10:\"07-08-2026\";i:6;s:10:\"07-09-2026\";i:7;s:10:\"07-10-2026\";i:10;s:10:\"07-11-2026\";i:6;s:10:\"07-12-2026\";i:3;s:10:\"07-13-2026\";i:7;s:10:\"07-14-2026\";i:5;s:10:\"07-15-2026\";i:5;}"],"houzez_recently_viewed":["2026-07-14 22:52:47"],"fave_property_location":["14.498508149446216,-90.79556416704318"],"fave_property_images":["24633","24643","24626","24630","24634","24628","24615","24640","24616","24617","24639","24618","24619","24620","24622","24623","24624","24625","24627","24632","24635","24614"],"_thumbnail_id":["24633"],"_elementor_global_class_usage_indexed":["1"],"_elementor_page_assets":["a:0:{}"]},"_links":{"self":[{"href":"https:\/\/antiguafinehomes.com\/es\/wp-json\/wp\/v2\/properties\/24644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/antiguafinehomes.com\/es\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/antiguafinehomes.com\/es\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/antiguafinehomes.com\/es\/wp-json\/wp\/v2\/users\/11"}],"version-history":[{"count":1,"href":"https:\/\/antiguafinehomes.com\/es\/wp-json\/wp\/v2\/properties\/24644\/revisions"}],"predecessor-version":[{"id":28079,"href":"https:\/\/antiguafinehomes.com\/es\/wp-json\/wp\/v2\/properties\/24644\/revisions\/28079"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/antiguafinehomes.com\/es\/wp-json\/wp\/v2\/media\/24633"}],"wp:attachment":[{"href":"https:\/\/antiguafinehomes.com\/es\/wp-json\/wp\/v2\/media?parent=24644"}],"wp:term":[{"taxonomy":"property_type","embeddable":true,"href":"https:\/\/antiguafinehomes.com\/es\/wp-json\/wp\/v2\/property_type?post=24644"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/antiguafinehomes.com\/es\/wp-json\/wp\/v2\/property_status?post=24644"},{"taxonomy":"property_feature","embeddable":true,"href":"https:\/\/antiguafinehomes.com\/es\/wp-json\/wp\/v2\/property_feature?post=24644"},{"taxonomy":"property_label","embeddable":true,"href":"https:\/\/antiguafinehomes.com\/es\/wp-json\/wp\/v2\/property_label?post=24644"},{"taxonomy":"property_state","embeddable":true,"href":"https:\/\/antiguafinehomes.com\/es\/wp-json\/wp\/v2\/property_state?post=24644"},{"taxonomy":"property_city","embeddable":true,"href":"https:\/\/antiguafinehomes.com\/es\/wp-json\/wp\/v2\/property_city?post=24644"},{"taxonomy":"property_area","embeddable":true,"href":"https:\/\/antiguafinehomes.com\/es\/wp-json\/wp\/v2\/property_area?post=24644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}